{"id":1318,"date":"2025-05-19T07:15:04","date_gmt":"2025-05-19T07:15:04","guid":{"rendered":"https:\/\/aicloud.mygptmeta.com\/archives\/1318"},"modified":"2025-05-19T07:15:04","modified_gmt":"2025-05-19T07:15:04","slug":"openai-%e6%96%b0%e4%b8%80%e4%bb%a3%e7%bc%96%e7%a8%8b%e9%9d%a9%e5%91%bd%ef%bc%9acodex-%e6%99%ba%e8%83%bd%e4%bd%93%e5%85%a8%e9%9d%a2%e8%a7%a3%e6%9e%90","status":"publish","type":"post","link":"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/1318","title":{"rendered":"OpenAI Nova gera\u00e7\u00e3o de revolu\u00e7\u00e3o na programa\u00e7\u00e3o: Codex Intelligence Body Analysis"},"content":{"rendered":"<p>A OpenAI lan\u00e7ou recentemente a muito aguardada intelig\u00eancia de programa\u00e7\u00e3o Codex, uma poderosa ferramenta integrada no ChatGPT que entrou oficialmente na fase de pr\u00e9-visualiza\u00e7\u00e3o de investiga\u00e7\u00e3o. Sendo um sistema de assist\u00eancia \u00e0 engenharia de software baseado na nuvem, espera-se que o Codex revolucione a forma como os programadores trabalham, melhore a efici\u00eancia da programa\u00e7\u00e3o e simplifique o processamento de tarefas complexas. Neste artigo, iremos apresentar uma an\u00e1lise exaustiva das carater\u00edsticas, dos princ\u00edpios de funcionamento e das aplica\u00e7\u00f5es pr\u00e1ticas desta tecnologia revolucion\u00e1ria.<\/p>\n\n\n\n<p>Entrada do s\u00edtio Web oficial:<a href=\"https:\/\/openai.com\/index\/openai-codex\/\">https:\/\/openai.com\/index\/openai-codex\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_145302_010.png\" alt=\"\" class=\"wp-image-1407\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-codex-\u667a\u80fd\u4f53-\u7f16\u7a0b\u65b0\u65f6\u4ee3\u7684\u5f00\u7aef\">Codex Intelligent Bodies: O in\u00edcio de uma nova era de programa\u00e7\u00e3o<\/h2>\n\n\n\n<p>A OpenAI lan\u00e7ou a intelig\u00eancia de programa\u00e7\u00e3o Codex em maio de 2025, ap\u00f3s a adi\u00e7\u00e3o da capacidade de liga\u00e7\u00e3o aos reposit\u00f3rios GitHub no ChatGPT. Trata-se de uma intelig\u00eancia de engenharia de software baseada na nuvem capaz de realizar uma variedade de tarefas de programa\u00e7\u00e3o, incluindo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Escrever novos m\u00f3dulos funcionais<\/li>\n\n\n\n<li>Corrigir erros e vulnerabilidades do c\u00f3digo<\/li>\n\n\n\n<li>Execu\u00e7\u00e3o da verifica\u00e7\u00e3o de testes<\/li>\n\n\n\n<li>Apresenta\u00e7\u00e3o de altera\u00e7\u00f5es de c\u00f3digo<\/li>\n\n\n\n<li>Gerir e executar v\u00e1rias tarefas de codifica\u00e7\u00e3o em simult\u00e2neo<\/li>\n<\/ul>\n\n\n\n<p>Ao contr\u00e1rio dos assistentes de programa\u00e7\u00e3o tradicionais, o Codex baseia-se no modelo codex-1 (que \u00e9 uma vers\u00e3o especializada do modelo o3 da OpenAI), optimizado especificamente para a engenharia de software, e \u00e9 treinado atrav\u00e9s da aprendizagem por refor\u00e7o num ambiente de programa\u00e7\u00e3o real, de modo a que o c\u00f3digo que gera reflicta os estilos de codifica\u00e7\u00e3o humanos, siga as instru\u00e7\u00f5es \u00e0 letra e possa ser testado repetidamente at\u00e9 atingir os resultados desejados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/90ba83f316c5e76066e539b23409a7d0.png\" alt=\"\" class=\"wp-image-1408\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-codex-\u5de5\u4f5c\u539f\u7406\u4e0e\u6838\u5fc3\u7279\u6027\">Como funciona o Codex e as suas principais carater\u00edsticas<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u5de5\u4f5c\u6d41\u7a0b\">fluxo de trabalho<\/h3>\n\n\n\n<p>O fluxo de trabalho do Codex foi concebido para ser simples e intuitivo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Acesso do utilizador ao Codex atrav\u00e9s da barra lateral do ChatGPT<\/li>\n\n\n\n<li>Introduza os seus requisitos e clique no bot\u00e3o \"C\u00f3digo\" para atribuir uma tarefa ou clique no bot\u00e3o \"P&amp;R\" para fazer uma pergunta relacionada com o c\u00f3digo.<\/li>\n\n\n\n<li>O Codex executa tarefas num ambiente de nuvem seguro e isolado que \u00e9 pr\u00e9-carregado com a base de c\u00f3digo do utilizador<\/li>\n\n\n\n<li>Os utilizadores podem acompanhar o progresso das tarefas em tempo real<\/li>\n\n\n\n<li>Ap\u00f3s a conclus\u00e3o da tarefa, o Codex confirma as altera\u00e7\u00f5es e fornece provas detalhadas da implementa\u00e7\u00e3o, incluindo registos de terminais e resultados de testes<\/li>\n\n\n\n<li>Os utilizadores podem rever os resultados, solicitar mais modifica\u00e7\u00f5es ou integrar as altera\u00e7\u00f5es no fluxo de trabalho<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u5173\u952e\u6280\u672f\u7279\u6027\">Principais carater\u00edsticas t\u00e9cnicas<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>carateriza\u00e7\u00e3o<\/th><th>descri\u00e7\u00f5es<\/th><\/tr><\/thead><tbody><tr><td><strong>multitarefa<\/strong><\/td><td>Capacidade para gerir simultaneamente v\u00e1rias tarefas de programa\u00e7\u00e3o independentes<\/td><\/tr><tr><td><strong>Executar na nuvem<\/strong><\/td><td>As tarefas s\u00e3o executadas em contentores de nuvem isolados de forma segura, sem ocupar recursos locais<\/td><\/tr><tr><td><strong>Integra\u00e7\u00e3o da base de c\u00f3digo<\/strong><\/td><td>Suporta a integra\u00e7\u00e3o perfeita com reposit\u00f3rios GitHub, permitindo a leitura e a manipula\u00e7\u00e3o diretas do c\u00f3digo do utilizador.<\/td><\/tr><tr><td><strong>Compreens\u00e3o inteligente de c\u00f3digos<\/strong><\/td><td>Capacidade para compreender estruturas de c\u00f3digo complexas, identificar potenciais problemas e apresentar solu\u00e7\u00f5es<\/td><\/tr><tr><td><strong>cadeia de cust\u00f3dia completa<\/strong><\/td><td>Fornecer provas verific\u00e1veis da execu\u00e7\u00e3o das tarefas atrav\u00e9s de registos de terminais, resultados de testes, etc.<\/td><\/tr><tr><td><strong>Configura\u00e7\u00e3o do ambiente<\/strong><\/td><td>Suporte para configura\u00e7\u00f5es personalizadas para adequar o ambiente \u00e0s defini\u00e7\u00f5es reais de desenvolvimento<\/td><\/tr><tr><td><strong>Seguran\u00e7a e prote\u00e7\u00e3o<\/strong><\/td><td>O acesso \u00e0 Internet \u00e9 desativado durante a execu\u00e7\u00e3o e a intera\u00e7\u00e3o com o c\u00f3digo e as depend\u00eancias explicitamente autorizadas \u00e9 limitada<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Vale a pena notar que o Codex suporta seguir o <code>AGENTES.md<\/code> Guias de documenta\u00e7\u00e3o, semelhantes a um programador humano que l\u00ea um ficheiro README para compreender as especifica\u00e7\u00f5es de um projeto. O Codex tem um melhor desempenho quando configurado corretamente, testado de forma fi\u00e1vel e claramente documentado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\u5b9e\u6218\u6848\u4f8b-codex-\u7f16\u7a0b\u80fd\u529b\u5c55\u793a\">Caso pr\u00e1tico: Demonstra\u00e7\u00e3o de compet\u00eancias de programa\u00e7\u00e3o do Codex<\/h2>\n\n\n\n<p>Abaixo est\u00e3o exemplos da utiliza\u00e7\u00e3o do Codex em projectos reais de c\u00f3digo aberto, demonstrando a sua capacidade de lidar com uma variedade de tarefas de programa\u00e7\u00e3o:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u6848\u4f8b\u4e00-\u4fee\u590d-astropy-\u5e93\u4e2d\u7684\u5d4c\u5957-compoundmodels-\u8ba1\u7b97\u95ee\u9898\">Caso 1: Corre\u00e7\u00e3o de um problema de c\u00e1lculo de CompoundModels aninhados na biblioteca astropy<\/h3>\n\n\n\n<p>Neste caso, o Codex precisava de resolver o problema de a separability_matrix do m\u00f3dulo Modeling no reposit\u00f3rio astropy\/astropy n\u00e3o estar a calcular corretamente a separabilidade dos CompoundModels aninhados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_141758_494.png\" alt=\"\" class=\"wp-image-1395\"\/><\/figure>\n\n\n\n<p>O Codex gerou uma modifica\u00e7\u00e3o de c\u00f3digo muito concisa e precisa, apenas com as altera\u00e7\u00f5es necess\u00e1rias ao n\u00facleo do problema. Em contrapartida, o esquema de modifica\u00e7\u00e3o do modelo o3 era mais longo e acrescentava mesmo alguns coment\u00e1rios desnecess\u00e1rios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_141954_982.png\" alt=\"\" class=\"wp-image-1397\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u6848\u4f8b\u4e8c-\u4fee\u590d-matplotlib-\u7a97\u53e3\u6821\u6b63\u9519\u8bef\">Caso 2: Corre\u00e7\u00e3o de erros de calibra\u00e7\u00e3o da janela matplotlib<\/h3>\n\n\n\n<p>Esta tarefa requer que a biblioteca matplotlib seja corrigida. <code>mlab._spectral_helper<\/code> A corre\u00e7\u00e3o da janela est\u00e1 incorrecta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_142825_171.png\" alt=\"\" class=\"wp-image-1398\"\/><\/figure>\n\n\n\n<p>O Codex tamb\u00e9m demonstra a capacidade de corrigir as coisas com precis\u00e3o e simplicidade, modificando apenas as linhas de c\u00f3digo necess\u00e1rias para manter a clareza e a facilidade de manuten\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_142923_566.png\" alt=\"\" class=\"wp-image-1399\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u6848\u4f8b\u4e09-\u89e3\u51b3-django-\u4e2d-duration-\u8868\u8fbe\u5f0f\u95ee\u9898\">Caso 3: Resolver o problema da express\u00e3o de dura\u00e7\u00e3o em django<\/h3>\n\n\n\n<p>Neste caso, foi necess\u00e1rio corrigir um problema na estrutura do django em que as express\u00f5es que continham apenas a dura\u00e7\u00e3o n\u00e3o funcionavam corretamente no SQLite e no MySQL.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_143553_445.png\" alt=\"\" class=\"wp-image-1400\"\/><\/figure>\n\n\n\n<p>O Codex n\u00e3o s\u00f3 fornece uma corre\u00e7\u00e3o limpa, como tamb\u00e9m preenche primeiro as chamadas de depend\u00eancia em falta, demonstrando a sua capacidade de compreender totalmente o contexto do c\u00f3digo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_143902_372_cleanup.png\" alt=\"\" class=\"wp-image-1401\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u6848\u4f8b\u56db-\u4fee\u590d-expensify-\u6210\u5458\u804a\u5929\u5ba4\u540d\u79f0\u66f4\u65b0\u95ee\u9898\">Caso 4: Corrigir o problema de atualiza\u00e7\u00e3o do nome da sala de chat dos membros do expensify<\/h3>\n\n\n\n<p>Este caso envolve um erro no expensify (um software de colabora\u00e7\u00e3o financeira centrado no chat): depois de apagar a cache, os nomes das salas de chat dos membros n\u00e3o eram actualizados no LHN.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_144339_227.png\" alt=\"\" class=\"wp-image-1402\"\/><\/figure>\n\n\n\n<p>O Codex identificou o problema e forneceu uma corre\u00e7\u00e3o precisa e eficaz, enquanto o modelo o3 fez algumas altera\u00e7\u00f5es ineficazes ao c\u00f3digo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/\u5fae\u4fe1\u56fe\u7247_2025-05-19_144847_301.png\" alt=\"\" class=\"wp-image-1404\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\u6027\u80fd\u8bc4\u4f30\u4e0e\u5bf9\u6bd4\u5206\u6790\">Avalia\u00e7\u00e3o do desempenho e an\u00e1lise comparativa<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u57fa\u51c6\u6d4b\u8bd5\u6210\u7ee9\">pontua\u00e7\u00e3o de base<\/h3>\n\n\n\n<p>No benchmark SWE-Bench Verified, o Codex (codex-1) obteve resultados impressionantes:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>modela\u00e7\u00e3o<\/th><th>Pontua\u00e7\u00e3o SWE-bench<\/th><\/tr><\/thead><tbody><tr><td><strong>Codex (codex-1)<\/strong><\/td><td>72.1%<\/td><\/tr><tr><td><strong>Claude 3.7<\/strong><\/td><td>62.3%<\/td><\/tr><tr><td><strong>o3-alto<\/strong><\/td><td>71.7%<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Os testes foram realizados com um comprimento de contexto de at\u00e9 192.000 tokens, utilizando uma defini\u00e7\u00e3o de \"esfor\u00e7o de infer\u00eancia\" m\u00e9dio, o mesmo que est\u00e1 atualmente dispon\u00edvel nas vers\u00f5es do produto Codex.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/school.myshirtai.com\/wp-content\/uploads\/2025\/05\/ef02800ccba70c30c5eb31bab6bf653f-realesr-animevideov3-x2-x2.png\" alt=\"\" class=\"wp-image-1396\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u4e0e-o3-\u6a21\u578b\u7684\u4ee3\u7801\u751f\u6210\u5bf9\u6bd4\">Compara\u00e7\u00e3o da gera\u00e7\u00e3o de c\u00f3digo com o modelo o3<\/h3>\n\n\n\n<p>Exemplos do mundo real demonstram que o codex-1 gera consistentemente patches de altera\u00e7\u00e3o de c\u00f3digo mais limpos e claros do que o OpenAI o3, que podem ser imediatamente revistos manualmente e integrados em fluxos de trabalho padr\u00e3o. Em v\u00e1rios testes de bibliotecas de c\u00f3digo aberto, o codex demonstrou maior precis\u00e3o e melhor qualidade de c\u00f3digo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u5b9e\u9645\u4f7f\u7528\u53cd\u9988\">Feedback sobre a utiliza\u00e7\u00e3o efectiva<\/h3>\n\n\n\n<p>A equipa interna da OpenAI adoptou o Codex como parte das suas ferramentas de desenvolvimento di\u00e1rias, principalmente para executar tarefas repetitivas e bem delimitadas, como a refac\u00e7\u00e3o de c\u00f3digo, a renomea\u00e7\u00e3o e a escrita de testes que normalmente interrompem o fluxo de concentra\u00e7\u00e3o de um programador.<\/p>\n\n\n\n<p>Al\u00e9m disso, os primeiros testes com v\u00e1rios parceiros externos, incluindo a Cisco, a Temporal, a Superhuman e a Kodiak, demonstraram que o Codex acelera significativamente tarefas como o desenvolvimento de funcionalidades, a depura\u00e7\u00e3o de problemas, a elabora\u00e7\u00e3o e execu\u00e7\u00e3o de testes e melhora a efici\u00eancia da equipa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\u53ef\u7528\u6027-\u5b9a\u4ef7\u4e0e\u672a\u6765\u5c55\u671b\">Disponibilidade, pre\u00e7os e perspectivas futuras<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u5f53\u524d\u53ef\u7528\u6027\">Disponibilidade atual<\/h3>\n\n\n\n<p>O Codex est\u00e1 aberto aos seguintes utilizadores:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Utilizadores do ChatGPT Pro ($200 por m\u00eas)<\/li>\n\n\n\n<li>Utilizadores do ChatGPT Enterprise<\/li>\n\n\n\n<li>Utilizadores da equipa ChatGPT<\/li>\n<\/ul>\n\n\n\n<p>Em breve, os utilizadores do ChatGPT Plus e do Edu tamb\u00e9m poder\u00e3o utilizar esta funcionalidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u5b9a\u4ef7\u7b56\u7565\">estrat\u00e9gia de pre\u00e7os<\/h3>\n\n\n\n<p>Atualmente, a OpenAI est\u00e1 a oferecer um per\u00edodo de teste gratuito em que os utilizadores podem experimentar a funcionalidade do Codex sem restri\u00e7\u00f5es durante as pr\u00f3ximas semanas. Depois disso, ser\u00e3o introduzidos limites de velocidade e op\u00e7\u00f5es flex\u00edveis de pagamento consoante o uso.<\/p>\n\n\n\n<p>Para os programadores, o modelo codex-mini-latest est\u00e1 dispon\u00edvel na API de respostas para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Token por milh\u00e3o de entradas: $1.50<\/li>\n\n\n\n<li>Token por milh\u00e3o de sa\u00edda: $6.00<\/li>\n\n\n\n<li>Desfrute de um desconto na cache de alerta do 75%<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-\u672a\u6765\u53d1\u5c55\u8def\u7ebf\">O caminho a seguir<\/h3>\n\n\n\n<p>A OpenAI planeia melhorar ainda mais a interatividade e a flexibilidade do Codex:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Apoio na presta\u00e7\u00e3o de orienta\u00e7\u00e3o e feedback durante a execu\u00e7\u00e3o do mandato<\/li>\n\n\n\n<li>Colaborar com a IA para implementar estrat\u00e9gias de programa\u00e7\u00e3o<\/li>\n\n\n\n<li>Receber notifica\u00e7\u00f5es proactivas de atualiza\u00e7\u00e3o do progresso<\/li>\n\n\n\n<li>Integra\u00e7\u00e3o profunda com ferramentas de desenvolvimento populares (por exemplo, GitHub, linha de comando, rastreadores de problemas, sistemas de CI)<\/li>\n<\/ol>\n\n\n\n<p>O lan\u00e7amento do Codex Intelligent Body marca uma nova etapa na programa\u00e7\u00e3o assistida por IA. Em vez de substituir os engenheiros, actua como um assistente fi\u00e1vel para tarefas entediantes e repetitivas, permitindo que os programadores se concentrem em trabalho mais criativo e estrat\u00e9gico. Embora ainda se encontre em fase de investiga\u00e7\u00e3o pr\u00e9via e tenha algumas limita\u00e7\u00f5es (por exemplo, falta de acesso \u00e0 Internet, longos tempos de resposta \u00e0s tarefas, etc.), o Codex demonstrou um grande potencial para remodelar a l\u00f3gica subjacente ao desenvolvimento de software e tornar-se uma parte importante do paradigma de programa\u00e7\u00e3o do futuro.<\/p>\n\n\n\n<table style=\"width: 100%;border-collapse: collapse;border: 1px solid #ddd\">\r\n<thead>\r\n<tr style=\"height: 48px;background-color: #f5f5f5\">\r\n<th style=\"width: 50%;height: 48px;border: 1px solid #ddd;padding: 8px\">\r\n<h4 style=\"margin: 0\">Para mais produtos, consultar<\/h4>\r\n<\/th>\r\n<th style=\"width: 50%;height: 48px;border: 1px solid #ddd;padding: 8px\">\r\n<h4 style=\"margin: 0\">Ver mais em<\/h4>\r\n<\/th>\r\n<\/tr>\r\n<\/thead>\r\n<tbody>\r\n<tr style=\"height: 63px\">\r\n<td style=\"width: 50%;height: 63px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.myshirtai.com\/\" data-linktype=\"2\">ShirtAI - Intelig\u00eancia penetrante<\/a><\/td>\r\n<td style=\"width: 50%;height: 63px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.myshirtai.com\/archives\/4425\" data-linktype=\"2\">O Grande Modelo do AIGC: inaugurando uma era de dupla revolu\u00e7\u00e3o na engenharia e na ci\u00eancia - Penetrating Intelligence<\/a><\/td>\r\n<\/tr>\r\n<tr style=\"height: 61px\">\r\n<td style=\"width: 50%;height: 61px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.myshirtai.com\/\" data-linktype=\"2\">1:1 Restaura\u00e7\u00e3o de Claude e GPT Site oficial - AI Cloud Native<\/a><\/td>\r\n<td style=\"width: 50%;height: 61px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.bluelsqkj.com\/archives\/2876\" data-linktype=\"2\">Aplica\u00e7\u00e3o de jogos em direto Leitor de visualiza\u00e7\u00e3o de desporto HD global (recomendado) - Blueshirt Technology<\/a><\/td>\r\n<\/tr>\r\n<tr style=\"height: 54px\">\r\n<td style=\"width: 50%;height: 54px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/api.mygptmeta.com\/\" data-linktype=\"2\">Servi\u00e7o de tr\u00e2nsito baseado na API oficial - API GPTMeta<\/a><\/td>\r\n<td style=\"width: 50%;height: 54px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.zhihu.com\/question\/621055223\/answer\/3633615705\" data-linktype=\"2\">Ajuda, algu\u00e9m pode dar algumas dicas sobre como fazer perguntas no GPT? - Conhecimento<\/a><\/td>\r\n<\/tr>\r\n<tr style=\"height: 70px\">\r\n<td style=\"width: 50%;height: 70px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/shop.blueshirtmap.com\/\" data-linktype=\"2\">Loja digital de bens virtuais globais - Global SmarTone (Feng Ling Ge)<\/a><\/td>\r\n<td style=\"width: 50%;height: 70px;border: 1px solid #ddd;padding: 8px\"><a href=\"https:\/\/www.bilibili.com\/video\/BV1efpneYE54\/?spm_id_from=333.1387.homepage.video_card.click\" data-linktype=\"2\">Qu\u00e3o poderosa \u00e9 a funcionalidade Claude airtfacts que o GPT instantaneamente n\u00e3o cheira bem? -BeepBeep<\/a><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","protected":false},"excerpt":{"rendered":"<p>A OpenAI lan\u00e7a a intelig\u00eancia de programa\u00e7\u00e3o Codex em maio de 2025, integrada com o ChatGPT e baseada no modelo codex-1, que executa tarefas como escrever c\u00f3digo, corrigir bugs, executar testes e muito mais, na nuvem. O codex suporta integra\u00e7\u00f5es do GitHub, fornece evid\u00eancias verific\u00e1veis de execu\u00e7\u00e3o e obteve 72.1% nos testes SWE-Bench. est\u00e1 atualmente dispon\u00edvel para usu\u00e1rios Pro, Enterprise e Team. O Codex est\u00e1 atualmente dispon\u00edvel para utilizadores Pro, Enterprise e Team e, no futuro, ir\u00e1 melhorar ainda mais a interatividade e a integra\u00e7\u00e3o de ferramentas de desenvolvimento para ajudar a melhorar a efici\u00eancia do desenvolvimento de software.<\/p>","protected":false},"author":1,"featured_media":1317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[52,53],"class_list":["post-1318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-codex-technology","tag-coding-agent"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790 - AI\u4e91\u539f\u751f<\/title>\n<meta name=\"description\" content=\"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/1318\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790\" \/>\n<meta property=\"og:description\" content=\"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/1318\/\" \/>\n<meta property=\"og:site_name\" content=\"AI\u4e91\u539f\u751f\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-19T07:15:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#article\",\"isPartOf\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/581e84c756e12026dca4a9a22c2097c7\"},\"headline\":\"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790\",\"datePublished\":\"2025-05-19T07:15:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318\"},\"wordCount\":123,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png\",\"keywords\":[\"Codex\u6280\u672f\",\"\u7f16\u7a0b\u667a\u80fd\u4f53\"],\"articleSection\":[\"\u535a\u5ba2\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318\",\"url\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318\",\"name\":\"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790 - AI\u4e91\u539f\u751f\",\"isPartOf\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png\",\"datePublished\":\"2025-05-19T07:15:04+00:00\",\"description\":\"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%\",\"breadcrumb\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aicloud.mygptmeta.com\/archives\/1318\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage\",\"url\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png\",\"contentUrl\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/archives\/1318#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/aicloud.mygptmeta.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#website\",\"url\":\"https:\/\/aicloud.mygptmeta.com\/\",\"name\":\"AI\u4e91\u539f\u751f\",\"description\":\"1:1\u8fd8\u539fClaude\u548cGPT\u5b98\u7f51\",\"publisher\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aicloud.mygptmeta.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#organization\",\"name\":\"AI\u4e91\u539f\u751f\",\"url\":\"https:\/\/aicloud.mygptmeta.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2024\/07\/AI-Cloud-169\u00d740.png\",\"contentUrl\":\"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2024\/07\/AI-Cloud-169\u00d740.png\",\"width\":169,\"height\":40,\"caption\":\"AI\u4e91\u539f\u751f\"},\"image\":{\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/581e84c756e12026dca4a9a22c2097c7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e40122f3ea588c331477d2b5778ab521f0ef9275880700b47f592c999e721b7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e40122f3ea588c331477d2b5778ab521f0ef9275880700b47f592c999e721b7?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\/\/aicloud.mygptmeta.com\"],\"url\":\"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/author\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790 - AI\u4e91\u539f\u751f","description":"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/1318\/","og_locale":"pt_PT","og_type":"article","og_title":"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790","og_description":"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%","og_url":"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/1318\/","og_site_name":"AI\u4e91\u539f\u751f","article_published_time":"2025-05-19T07:15:04+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#article","isPartOf":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318"},"author":{"name":"admin","@id":"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/581e84c756e12026dca4a9a22c2097c7"},"headline":"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790","datePublished":"2025-05-19T07:15:04+00:00","mainEntityOfPage":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318"},"wordCount":123,"commentCount":0,"publisher":{"@id":"https:\/\/aicloud.mygptmeta.com\/#organization"},"image":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage"},"thumbnailUrl":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png","keywords":["Codex\u6280\u672f","\u7f16\u7a0b\u667a\u80fd\u4f53"],"articleSection":["\u535a\u5ba2"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aicloud.mygptmeta.com\/archives\/1318#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318","url":"https:\/\/aicloud.mygptmeta.com\/archives\/1318","name":"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790 - AI\u4e91\u539f\u751f","isPartOf":{"@id":"https:\/\/aicloud.mygptmeta.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage"},"image":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage"},"thumbnailUrl":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png","datePublished":"2025-05-19T07:15:04+00:00","description":"OpenAI \u4e8e2025\u5e745\u6708\u63a8\u51fa Codex \u7f16\u7a0b\u667a\u80fd\u4f53\uff0c\u96c6\u6210\u4e8e ChatGPT\uff0c\u57fa\u4e8e codex-1 \u6a21\u578b\uff0c\u5728\u4e91\u7aef\u6267\u884c\u7f16\u5199\u4ee3\u7801\u3001\u4fee\u590d\u6f0f\u6d1e\u3001\u8fd0\u884c\u6d4b\u8bd5\u7b49\u4efb\u52a1\u3002Codex \u652f\u6301 GitHub \u96c6\u6210\uff0c\u63d0\u4f9b\u53ef\u9a8c\u8bc1\u7684\u6267\u884c\u8bc1\u636e\uff0c\u5e76\u5728 SWE-Bench \u6d4b\u8bd5\u4e2d\u5f97\u5206\u8fbe 72.1%","breadcrumb":{"@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aicloud.mygptmeta.com\/archives\/1318"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#primaryimage","url":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png","contentUrl":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2025\/05\/2025-05-19_150853_905.png","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/aicloud.mygptmeta.com\/archives\/1318#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/aicloud.mygptmeta.com\/"},{"@type":"ListItem","position":2,"name":"OpenAI \u65b0\u4e00\u4ee3\u7f16\u7a0b\u9769\u547d\uff1aCodex \u667a\u80fd\u4f53\u5168\u9762\u89e3\u6790"}]},{"@type":"WebSite","@id":"https:\/\/aicloud.mygptmeta.com\/#website","url":"https:\/\/aicloud.mygptmeta.com\/","name":"AI\u4e91\u539f\u751f","description":"1:1\u8fd8\u539fClaude\u548cGPT\u5b98\u7f51","publisher":{"@id":"https:\/\/aicloud.mygptmeta.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aicloud.mygptmeta.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/aicloud.mygptmeta.com\/#organization","name":"AI\u4e91\u539f\u751f","url":"https:\/\/aicloud.mygptmeta.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aicloud.mygptmeta.com\/#\/schema\/logo\/image\/","url":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2024\/07\/AI-Cloud-169\u00d740.png","contentUrl":"https:\/\/aicloud.mygptmeta.com\/wp-content\/uploads\/2024\/07\/AI-Cloud-169\u00d740.png","width":169,"height":40,"caption":"AI\u4e91\u539f\u751f"},"image":{"@id":"https:\/\/aicloud.mygptmeta.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/581e84c756e12026dca4a9a22c2097c7","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/aicloud.mygptmeta.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0e40122f3ea588c331477d2b5778ab521f0ef9275880700b47f592c999e721b7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e40122f3ea588c331477d2b5778ab521f0ef9275880700b47f592c999e721b7?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/aicloud.mygptmeta.com"],"url":"https:\/\/aicloud.mygptmeta.com\/pt\/archives\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/posts\/1318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/comments?post=1318"}],"version-history":[{"count":0,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/posts\/1318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/media\/1317"}],"wp:attachment":[{"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/media?parent=1318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/categories?post=1318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aicloud.mygptmeta.com\/pt\/wp-json\/wp\/v2\/tags?post=1318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}